{"id":232,"count":20,"description":"","link":"https:\/\/www.preciosboom.com\/ca\/product-category\/juguetes\/","name":"Joguines","slug":"juguetes","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_cat\/232"}],"collection":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product?product_cat=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}