{"id":18614,"date":"2026-03-25T14:43:59","date_gmt":"2026-03-25T13:43:59","guid":{"rendered":"https:\/\/www.preciosboom.com\/?post_type=product&#038;p=18614"},"modified":"2026-03-26T11:12:56","modified_gmt":"2026-03-26T10:12:56","slug":"pelota-14-cms","status":"publish","type":"product","link":"https:\/\/www.preciosboom.com\/ca\/product\/pelota-14-cms\/","title":{"rendered":"Pelota 14 cms"},"content":{"rendered":"<p>Pelota de 14 cm, perfecta para los peque\u00f1os fans de la serie. Con un dise\u00f1o colorido protagonizado por sus personajes favoritos, esta pelota es ideal para juegos al aire libre o en casa. Su tama\u00f1o es c\u00f3modo para manos infantiles, fomentando la actividad f\u00edsica, la coordinaci\u00f3n y la diversi\u00f3n en cualquier momento. Ligera y resistente, es un accesorio perfecto para horas de entretenimiento.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"flex flex-col text-sm\">\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:229b2224-5a55-4891-a250-15f7d8bf6ec2-14\" data-testid=\"conversation-turn-30\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"f4964a55-7b19-4bb1-a776-765513b57b56\" data-message-model-slug=\"gpt-5-mini\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"476\" data-end=\"609\" data-is-last-node=\"\" data-is-only-node=\"\">Pelota de 14 cm, colorida y divertida, ideal para juegos y entretenimiento de los m\u00e1s peque\u00f1os.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"pointer-events-none h-px w-px absolute bottom-0\" aria-hidden=\"true\" data-edge=\"true\"><\/div>","protected":false},"featured_media":18616,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[213,110],"product_tag":[],"class_list":{"0":"post-18614","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-balones_playa","7":"product_cat-deporte","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product\/18614"}],"collection":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/comments?post=18614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/media\/18616"}],"wp:attachment":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/media?parent=18614"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_brand?post=18614"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_cat?post=18614"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_tag?post=18614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}