{"id":18588,"date":"2026-03-25T14:23:08","date_gmt":"2026-03-25T13:23:08","guid":{"rendered":"https:\/\/www.preciosboom.com\/?post_type=product&#038;p=18588"},"modified":"2026-03-26T12:09:33","modified_gmt":"2026-03-26T11:09:33","slug":"mandalas-gruesas-flecos-surtidas","status":"publish","type":"product","link":"https:\/\/www.preciosboom.com\/ca\/product\/mandalas-gruesas-flecos-surtidas\/","title":{"rendered":"Mandalas gruesos flecos surtidas"},"content":{"rendered":"<p>Mandala gruesa con flecos surtidos, dise\u00f1ada para aportar un toque artesanal y lleno de color a cualquier espacio. Su tejido resistente y de calidad, junto con sus detalles en flecos, crea una pieza decorativa \u00fanica y llamativa. Ideal para usar como elemento decorativo en el hogar, tapete o accesorio vers\u00e1til, destaca por sus dise\u00f1os variados que se adaptan a diferentes estilos y ambientes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mandala gruesa con flecos surtidos, colorida y resistente, perfecta para decorar con estilo y originalidad.<\/p>","protected":false},"featured_media":18589,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[218,113],"product_tag":[],"class_list":{"0":"post-18588","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-toallas","7":"product_cat-verano_playa","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product\/18588"}],"collection":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/comments?post=18588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/media\/18589"}],"wp:attachment":[{"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/media?parent=18588"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_brand?post=18588"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_cat?post=18588"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.preciosboom.com\/ca\/wp-json\/wp\/v2\/product_tag?post=18588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}